{"id":126,"count":42,"description":"","link":"https:\/\/www.inaba-ciao.com\/en\/product-category\/pet-products\/cat\/creamy-treat-cat\/","name":"Creamy Treat","slug":"creamy-treat-cat","taxonomy":"product_cat","parent":132,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Creamy Treat Archives - inaba-foods<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.inaba-ciao.com\/en\/product-category\/pet-products\/cat\/creamy-treat-cat\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Creamy Treat Archives - inaba-foods\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.inaba-ciao.com\/en\/product-category\/pet-products\/cat\/creamy-treat-cat\/\" \/>\n<meta property=\"og:site_name\" content=\"inaba-foods\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.inaba-ciao.com\\\/en\\\/product-category\\\/pet-products\\\/cat\\\/creamy-treat-cat\\\/\",\"url\":\"https:\\\/\\\/www.inaba-ciao.com\\\/en\\\/product-category\\\/pet-products\\\/cat\\\/creamy-treat-cat\\\/\",\"name\":\"Creamy Treat Archives - inaba-foods\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.inaba-ciao.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.inaba-ciao.com\\\/en\\\/product-category\\\/pet-products\\\/cat\\\/creamy-treat-cat\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.inaba-ciao.com\\\/en\\\/product-category\\\/pet-products\\\/cat\\\/creamy-treat-cat\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.inaba-ciao.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pet Products\",\"item\":\"https:\\\/\\\/www.inaba-ciao.com\\\/en\\\/product-category\\\/pet-products\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cat\",\"item\":\"https:\\\/\\\/www.inaba-ciao.com\\\/en\\\/product-category\\\/pet-products\\\/cat\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Creamy Treat\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.inaba-ciao.com\\\/#website\",\"url\":\"https:\\\/\\\/www.inaba-ciao.com\\\/\",\"name\":\"inaba-foods\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.inaba-ciao.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.inaba-ciao.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.inaba-ciao.com\\\/#organization\",\"name\":\"inaba-foods\",\"url\":\"https:\\\/\\\/www.inaba-ciao.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.inaba-ciao.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.inaba-ciao.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Untitled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.inaba-ciao.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Untitled-1.jpg\",\"width\":300,\"height\":150,\"caption\":\"inaba-foods\"},\"image\":{\"@id\":\"https:\\\/\\\/www.inaba-ciao.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/inabaciao.th\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Creamy Treat Archives - inaba-foods","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.inaba-ciao.com\/en\/product-category\/pet-products\/cat\/creamy-treat-cat\/","og_locale":"en_US","og_type":"article","og_title":"Creamy Treat Archives - inaba-foods","og_url":"https:\/\/www.inaba-ciao.com\/en\/product-category\/pet-products\/cat\/creamy-treat-cat\/","og_site_name":"inaba-foods","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.inaba-ciao.com\/en\/product-category\/pet-products\/cat\/creamy-treat-cat\/","url":"https:\/\/www.inaba-ciao.com\/en\/product-category\/pet-products\/cat\/creamy-treat-cat\/","name":"Creamy Treat Archives - inaba-foods","isPartOf":{"@id":"https:\/\/www.inaba-ciao.com\/#website"},"breadcrumb":{"@id":"https:\/\/www.inaba-ciao.com\/en\/product-category\/pet-products\/cat\/creamy-treat-cat\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.inaba-ciao.com\/en\/product-category\/pet-products\/cat\/creamy-treat-cat\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.inaba-ciao.com\/en\/"},{"@type":"ListItem","position":2,"name":"Pet Products","item":"https:\/\/www.inaba-ciao.com\/en\/product-category\/pet-products\/"},{"@type":"ListItem","position":3,"name":"Cat","item":"https:\/\/www.inaba-ciao.com\/en\/product-category\/pet-products\/cat\/"},{"@type":"ListItem","position":4,"name":"Creamy Treat"}]},{"@type":"WebSite","@id":"https:\/\/www.inaba-ciao.com\/#website","url":"https:\/\/www.inaba-ciao.com\/","name":"inaba-foods","description":"","publisher":{"@id":"https:\/\/www.inaba-ciao.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.inaba-ciao.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.inaba-ciao.com\/#organization","name":"inaba-foods","url":"https:\/\/www.inaba-ciao.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.inaba-ciao.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.inaba-ciao.com\/wp-content\/uploads\/2026\/02\/Untitled-1.jpg","contentUrl":"https:\/\/www.inaba-ciao.com\/wp-content\/uploads\/2026\/02\/Untitled-1.jpg","width":300,"height":150,"caption":"inaba-foods"},"image":{"@id":"https:\/\/www.inaba-ciao.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/inabaciao.th"]}]}},"_links":{"self":[{"href":"https:\/\/www.inaba-ciao.com\/en\/wp-json\/wp\/v2\/product_cat\/126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inaba-ciao.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.inaba-ciao.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.inaba-ciao.com\/en\/wp-json\/wp\/v2\/product_cat\/132"}],"wp:post_type":[{"href":"https:\/\/www.inaba-ciao.com\/en\/wp-json\/wp\/v2\/product?product_cat=126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}